{"id":1152,"date":"2021-08-31T18:27:33","date_gmt":"2021-08-31T21:27:33","guid":{"rendered":"https:\/\/imais.online\/portal\/?p=1152"},"modified":"2021-08-31T18:27:34","modified_gmt":"2021-08-31T21:27:34","slug":"funssol-recebe-doacoes-de-r10-mil-em-vale-compras-do-supermercado-sao-vicente","status":"publish","type":"post","link":"https:\/\/imais.online\/portal\/funssol-recebe-doacoes-de-r10-mil-em-vale-compras-do-supermercado-sao-vicente\/","title":{"rendered":"Funssol recebe doa\u00e7\u00f5es de R$10 mil em vale compras do Supermercado S\u00e3o Vicente"},"content":{"rendered":"<div class=\"imais-before-content-placement\" id=\"imais-881121101\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8787528412751566\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8787528412751566\" \ndata-ad-slot=\"\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>\n<p class=\"has-text-align-center\"><strong>Cem fam\u00edlias ser\u00e3o beneficiadas com o valor de R$100<\/strong><\/p>\n\n\n\n<p>Na manh\u00e3 de ter\u00e7a-feira (31), o diretor de opera\u00e7\u00f5es da unidade de Indaiatuba da Rede de Supermercado S\u00e3o Vicente, Mauricio Cavicchiolli, esteve presente no Funssol (Fundo Social de Solidariedade) para doar R$ 10 mil em vale compras. Com isso, 100 fam\u00edlias que est\u00e3o em situa\u00e7\u00e3o de vulnerabilidade social ser\u00e3o beneficiadas com o valor de R$100 para&nbsp; que sejam utilizados, de acordo com a necessidade.<\/p>\n\n\n\n<p>\u201cAdquirimos mil cart\u00f5es. Agora, distribuiremos nas cidades que temos a unidade do Supermercado S\u00e3o Vicente, que \u00e9 o caso de Indaiatuba. Estamos repassando ao Fundo Social&nbsp; para serem entregues \u00e0s fam\u00edlias em vulnerabilidade. Na verdade, essa a\u00e7\u00e3o surgiu junto com a Associa\u00e7\u00e3o Paulista de Supermercados com a ideia do #SUPERESSENCIAL, criado durante a pandemia, para atender a&nbsp; necessidade de ajudar as pessoas por conta do impacto econ\u00f4mico causado. Assim, a empresa compra esse cart\u00e3o e disponibiliza para quem realmente precisa\u201d, explica Cavicchiolli.<\/p>\n\n\n\n<p>As fam\u00edlias contempladas ser\u00e3o escolhidas pelo Fundo Social, por meio de triagem, e receber\u00e3o o <em>voucher<\/em> com validade at\u00e9 o m\u00eas de outubro para comprar alimentos, mantimentos, itens de higiene pessoal ou&nbsp; produtos de limpeza. N\u00e3o \u00e9 permitida a compra de bebidas alco\u00f3licas ou cigarro.<\/p>\n\n\n\n<p>A presidente do Funssol, Maria das Gra\u00e7as Ara\u00fajo Massimo, destaca a import\u00e2ncia deste ato para a autoestima das pessoas que est\u00e3o passando por dificuldade financeira. \u201c\u00c9 importante voc\u00ea doar um produto, mas dar as pessoas a possibilidade de irem at\u00e9 o supermercado e poder escolher os produtos, isso faz uma grande diferen\u00e7a , inclusive para a autoestima do cidad\u00e3o. D\u00e1&nbsp; mais dignidade \u00e0s pessoas nessa \u00e9poca de pandemia. S\u00f3 temos a agradecer o Supermercado S\u00e3o Vicente\u201d, pontua.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cem fam\u00edlias ser\u00e3o beneficiadas com o valor de R$100 Na manh\u00e3 de ter\u00e7a-feira (31), o diretor de opera\u00e7\u00f5es da unidade de Indaiatuba da Rede de Supermercado S\u00e3o Vicente, Mauricio Cavicchiolli, esteve presente no Funssol (Fundo Social de Solidariedade) para doar R$ 10 mil em vale compras. Com isso, 100 fam\u00edlias que est\u00e3o em situa\u00e7\u00e3o de [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":1153,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[188],"tags":[],"class_list":["post-1152","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-indaiatuba"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/posts\/1152","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/comments?post=1152"}],"version-history":[{"count":1,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/posts\/1152\/revisions"}],"predecessor-version":[{"id":1154,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/posts\/1152\/revisions\/1154"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/media\/1153"}],"wp:attachment":[{"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/media?parent=1152"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/categories?post=1152"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/tags?post=1152"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}