{"id":1158,"date":"2021-08-31T18:38:21","date_gmt":"2021-08-31T21:38:21","guid":{"rendered":"https:\/\/imais.online\/portal\/?p=1158"},"modified":"2021-08-31T18:39:42","modified_gmt":"2021-08-31T21:39:42","slug":"governo-de-sp-inicia-contagem-regressiva-para-abertura-do-portal-museu-do-ipiranga","status":"publish","type":"post","link":"https:\/\/imais.online\/portal\/governo-de-sp-inicia-contagem-regressiva-para-abertura-do-portal-museu-do-ipiranga\/","title":{"rendered":"Governo de SP inicia contagem regressiva para abertura do portal Museu do Ipiranga"},"content":{"rendered":"<div class=\"imais-before-content-placement\" id=\"imais-1995548115\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8787528412751566\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8787528412751566\" \ndata-ad-slot=\"\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>\n<p class=\"has-text-align-center\">Com 70% das obras conclu\u00eddas, institui\u00e7\u00e3o ser\u00e1 reaberta em 372 dias<\/p>\n\n\n\n<p>O Governador Jo\u00e3o Doria anunciou nesta ter\u00e7a-feira (31) o in\u00edcio da contagem regressiva para entrega do portal Museu do Ipiranga que atualmente est\u00e1 com 70% das obras conclu\u00eddas. A institui\u00e7\u00e3o entra agora na etapa de restauro e recupera\u00e7\u00e3o do Jardim Franc\u00eas, que foi integrado ao projeto de restauro do museu. A reabertura acontecer\u00e1 em setembro de 2022 para a celebra\u00e7\u00e3o do bicenten\u00e1rio da Independ\u00eancia do Brasil.<\/p>\n\n\n\n<p>\u201cAno que vem teremos uma grande festividade. A proposta do governo de S\u00e3o Paulo \u00e9 um m\u00eas de festividades e atividades. Na parte externa, a partir de 7 de agosto, e na parte interna, a partir de 7 de setembro. Uma celebra\u00e7\u00e3o de verdade, aut\u00eantica, dos 200 anos da nossa independ\u00eancia\u201d, afirmou o Governador.<\/p>\n\n\n\n<p>O projeto prev\u00ea a restaura\u00e7\u00e3o de toda a \u00e1rea constru\u00edda e bot\u00e2nica do Jardim Franc\u00eas, al\u00e9m da constru\u00e7\u00e3o de um restaurante com 270m\u00b2, espa\u00e7o para food bikes, moderniza\u00e7\u00e3o da ilumina\u00e7\u00e3o, requalifica\u00e7\u00e3o das vias de acesso e o resgate de duas fontes do projeto original, demolidas em 1972.<\/p>\n\n\n\n<p>\u201cTemos um conjunto de interven\u00e7\u00f5es acontecendo simultaneamente: o restauro e amplia\u00e7\u00e3o do Edif\u00edcio Monumento, a reforma do Jardim Franc\u00eas, a recupera\u00e7\u00e3o do entorno, do Monumento da Independ\u00eancia, da Cripta Imperial e da Casa do Grito a cargo da prefeitura, a despolui\u00e7\u00e3o do C\u00f3rrego do Ipiranga e a cria\u00e7\u00e3o de uma nova \u00e1rea de lazer a cargo da Sabesp e a implanta\u00e7\u00e3o de um portal modelo de gest\u00e3o e sustentabilidade do museu\u201d, detalhou S\u00e9rgio S\u00e1 Leit\u00e3o, Secret\u00e1rio de Cultura e Economia Criativa.<\/p>\n\n\n\n<p>O investimento total nas obras \u00e9 de R$ 210 milh\u00f5es, dos quais R$ 170 milh\u00f5es foram captados junto \u00e0 iniciativa privada \u2013 com e sem Lei Rouanet. O valor investido pelo Governo de S\u00e3o Paulo \u00e9 de R$ 19 milh\u00f5es, por meio de conv\u00eanio entre a Secretaria de Cultura e Economia Criativa e a Funda\u00e7\u00e3o de Apoio \u00e0 USP, respons\u00e1vel pela gest\u00e3o do projeto, al\u00e9m de um aporte de R$ 11 milh\u00f5es da USP.<\/p>\n\n\n\n<p><strong>portal Museu do Ipiranga<\/strong><\/p>\n\n\n\n<p>A obra, iniciada em outubro de 2019, \u00e9 executada em duas frentes: amplia\u00e7\u00e3o e restauro do Edif\u00edcio Monumento. Na parte da amplia\u00e7\u00e3o, foi realizada uma escava\u00e7\u00e3o em frente ao pr\u00e9dio, que abrigar\u00e1 a nova entrada, bilheteria, audit\u00f3rio para 200 pessoas, espa\u00e7o do educativo, caf\u00e9, loja e sala de exposi\u00e7\u00e3o tempor\u00e1ria.<\/p>\n\n\n\n<p>J\u00e1 no restauro, est\u00e3o sendo realizados reparos em todos os detalhes da arquitetura, incluindo a fachada, os interiores e os elementos de marcenaria, como portas e batentes. Quando reaberto, o portal Museu do Ipiranga ter\u00e1 dobrado sua \u00e1rea total constru\u00edda, e modernizado o espa\u00e7o com elevadores, escadas rolantes e sistema de ar-condicionado.<\/p>\n\n\n\n<p>\u201cO museu n\u00e3o est\u00e1 sendo s\u00f3 restaurado e ampliado, ele est\u00e1 passando por importantes interven\u00e7\u00f5es para ser entregue com total acessibilidade e sustentabilidade. Uma nova iniciativa que certamente vai deixar o povo paulista, o povo brasileiro, muito orgulhoso\u201c, pontuou Vahan Agopyan, reitor da USP.<\/p>\n\n\n\n<p><strong>Programa\u00e7\u00e3o<\/strong><\/p>\n\n\n\n<p>No dia 7 de setembro, o Museu contar\u00e1 com uma programa\u00e7\u00e3o especial para comemorar o Dia da Independ\u00eancia. A institui\u00e7\u00e3o vai lan\u00e7ar um pocket show gravado por Jo\u00e3o Bosco no Edif\u00edcio Monumento em homenagem a Aldir Blanc e com participa\u00e7\u00e3o de Mart\u2019n\u00e1lia, \u00e0s 19h, no Facebook e no Instagram do Museu. Tamb\u00e9m vai inaugurar um totem com um rel\u00f3gio com a contagem regressiva para a reabertura do espa\u00e7o.<\/p>\n\n\n\n<p>Tamb\u00e9m ser\u00e3o lan\u00e7ados o game \u201cMuseu sob Ataque\u201d; uma s\u00e9rie de 12 v\u00eddeos sobre as obras mais ic\u00f4nicas do acervo, com o contador de hist\u00f3rias e influenciador digital Ivan Mesquita, divulgados mensalmente nas redes sociais; e proje\u00e7\u00f5es de cinco obras em fachadas de pr\u00e9dios em pontos diferentes da cidade, entre os dias 3 e 7 de setembro, das 19h \u00e0s 21h.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Com 70% das obras conclu\u00eddas, institui\u00e7\u00e3o ser\u00e1 reaberta em 372 dias O Governador Jo\u00e3o Doria anunciou nesta ter\u00e7a-feira (31) o in\u00edcio da contagem regressiva para entrega do portal Museu do Ipiranga que atualmente est\u00e1 com 70% das obras conclu\u00eddas. A institui\u00e7\u00e3o entra agora na etapa de restauro e recupera\u00e7\u00e3o do Jardim Franc\u00eas, que foi integrado [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":1159,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[195],"tags":[],"class_list":["post-1158","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sao-paulo"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/posts\/1158","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/comments?post=1158"}],"version-history":[{"count":1,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/posts\/1158\/revisions"}],"predecessor-version":[{"id":1160,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/posts\/1158\/revisions\/1160"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/media\/1159"}],"wp:attachment":[{"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/media?parent=1158"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/categories?post=1158"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/tags?post=1158"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}