{"id":1394,"date":"2021-09-13T17:38:48","date_gmt":"2021-09-13T20:38:48","guid":{"rendered":"https:\/\/imais.online\/portal\/?p=1394"},"modified":"2021-09-13T17:38:50","modified_gmt":"2021-09-13T20:38:50","slug":"toyota-suspendera-operacao-de-fabrica-em-indaiatuba-em-outubro","status":"publish","type":"post","link":"https:\/\/imais.online\/portal\/toyota-suspendera-operacao-de-fabrica-em-indaiatuba-em-outubro\/","title":{"rendered":"Toyota suspender\u00e1 opera\u00e7\u00e3o de f\u00e1brica em Indaiatuba em outubro"},"content":{"rendered":"<div class=\"imais-before-content-placement\" id=\"imais-2157346650\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8787528412751566\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8787528412751566\" \ndata-ad-slot=\"\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>\n<p>A Toyota anunciou nesta segunda-feira a suspens\u00e3o da produ\u00e7\u00e3o em sua f\u00e1brica de Indaiatuba (SP), onde fabrica o sed\u00e3 Corolla, entre 13 e 22 de outubro, alegando falta de insumos.<\/p>\n\n\n\n<p>&#8220;Apesar de todos os esfor\u00e7os que temos realizado ao longo do tempo para gerenciar a falta de insumos que afeta a cadeia de suprimentos global, provocada pela pandemia de Covid-19, uma nova parada \u00e9 inevit\u00e1vel&#8221;, afirmou a montadora, em nota.<\/p>\n\n\n\n<p>Procurada pela Reuters, a companhia n\u00e3o respondeu de imediato quais materiais est\u00e3o faltando.<\/p>\n\n\n\n<p>A Toyota acrescentou que os empregados da unidade entrar\u00e3o em f\u00e9rias coletivas no per\u00edodo, voltando ao trabalho em 25 de outubro. As demais unidades da Toyota no pa\u00eds &#8211; S\u00e3o Bernardo do Campo, Porto Feliz e Sorocaba &#8211; seguem com atividades normais.<\/p>\n\n\n\n<p>No come\u00e7o do m\u00eas, a montadora japonesa havia anunciado que sua planta de Sorocaba (SP) come\u00e7aria a produzir em tr\u00eas turnos a partir de janeiro de 2022, na contram\u00e3o de an\u00fancios de cortes na produ\u00e7\u00e3o de autom\u00f3veis por causa da escassez de chips.<\/p>\n\n\n\n<p>Via Terra<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Toyota anunciou nesta segunda-feira a suspens\u00e3o da produ\u00e7\u00e3o em sua f\u00e1brica de Indaiatuba (SP), onde fabrica o sed\u00e3 Corolla, entre 13 e 22 de outubro, alegando falta de insumos. &#8220;Apesar de todos os esfor\u00e7os que temos realizado ao longo do tempo para gerenciar a falta de insumos que afeta a cadeia de suprimentos global, [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":1395,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[188],"tags":[73,207],"class_list":["post-1394","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-indaiatuba","tag-featured","tag-indaiatuba"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/posts\/1394","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/comments?post=1394"}],"version-history":[{"count":1,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/posts\/1394\/revisions"}],"predecessor-version":[{"id":1396,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/posts\/1394\/revisions\/1396"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/media\/1395"}],"wp:attachment":[{"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/media?parent=1394"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/categories?post=1394"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/tags?post=1394"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}