{"id":1400,"date":"2021-09-13T18:13:27","date_gmt":"2021-09-13T21:13:27","guid":{"rendered":"https:\/\/imais.online\/portal\/?p=1400"},"modified":"2021-09-13T18:13:28","modified_gmt":"2021-09-13T21:13:28","slug":"sebrae-aqui-abre-curso-para-pessoas-que-querem-aprender-vender-material-de-construcao","status":"publish","type":"post","link":"https:\/\/imais.online\/portal\/sebrae-aqui-abre-curso-para-pessoas-que-querem-aprender-vender-material-de-construcao\/","title":{"rendered":"Sebrae Aqui abre curso para pessoas que querem aprender vender material de constru\u00e7\u00e3o"},"content":{"rendered":"<div class=\"imais-before-content-placement\" id=\"imais-2521080034\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8787528412751566\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8787528412751566\" \ndata-ad-slot=\"\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>\n<p class=\"has-text-align-center\"><strong>Inscri\u00e7\u00f5es devem ser realizadas com agendamento no Educand\u00e1rio Deus e a Natureza<\/strong><\/p>\n\n\n<p>A Secretaria de Governo de Indaiatuba, por meio do Sebrae aqui e do Senac, abre as inscri\u00e7\u00f5es para o curso \u201cAprenda a vender material de constru\u00e7\u00e3o\u201d. As aulas acontecer\u00e3o de forma presencial e gratuita, no Educand\u00e1rio Deus e a Natureza, do dia 4 at\u00e9 27 de outubro. Ser\u00e3o 11 encontros no hor\u00e1rio das 18h \u00e0s 22h, as segundas, quartas e sextas-feiras.<br \/><br \/>O objetivo \u00e9 preparar o participante para atuar na \u00e1rea de vendas de materiais de constru\u00e7\u00e3o, por meio de uma abordagem direta, apresentando as caracter\u00edsticas, especifica\u00e7\u00f5es, manuseio e armazenamento dos produtos, bem como as t\u00e9cnicas de vendas e negocia\u00e7\u00e3o, visando prestar um atendimento consultivo e a fideliza\u00e7\u00e3o de clientes.<br \/><br \/>No decorrer do curso os alunos v\u00e3o ter atividades que ensinar\u00e3o sobre estrat\u00e9gias participativas e diversificadas de aprendizage como: din\u00e2micas de grupos, jogos, leitura e interpreta\u00e7\u00e3o de textos, discuss\u00e3o e debate, estudo de casos, simula\u00e7\u00f5es, an\u00e1lise e interpreta\u00e7\u00e3o de filmes e m\u00fasicas, atividades de sistematiza\u00e7\u00e3o e constru\u00e7\u00e3o de conceitos.<br \/>As inscri\u00e7\u00f5es devem ser realizadas no Educand\u00e1rio Deus e a Natureza, com agendamento pelo telefone (19) 3875-4288. Candidato para esse curso deve ser maior de 18 anos.<\/p>\n<p><strong>CONTE\u00daDO PROGRAM\u00c1TICO:<\/strong><br \/>Etapas do processo de vendas: da abordagem ao p\u00f3s-venda<br \/>T\u00e9cnicas e estrat\u00e9gias de negocia\u00e7\u00e3o<br \/>\u00c9tica na rela\u00e7\u00e3o comercial<br \/>Caracter\u00edsticas de produtos de acordo com a natureza da obra e conhecimentos b\u00e1sicos dos processos de constru\u00e7\u00e3o<br \/>Possibilidades de atua\u00e7\u00e3o no mundo do trabalho<br \/>Sa\u00fade e Seguran\u00e7a no trabalho<\/p>\n<p><strong>SERVI\u00c7O:<\/strong><br \/>DATA: de 4 de outubro \u00e0 27 de outubro (segunda\/ quarta e sexta)<br \/>HOR\u00c1RIO: das 18h \u00e0s 22h<br \/>LOCAL: Educand\u00e1rio Deus e a Natureza &#8211; Rua Pedro Savian, n\u00ba 139 &#8211; Jardim Adriana<br \/>INSCRI\u00c7\u00d5ES: somente com agendamento no Educand\u00e1rio Deus e a Natureza (maiores de 18 anos).<br \/>TELEFONE: (19) 3875-4288<\/p>\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Inscri\u00e7\u00f5es devem ser realizadas com agendamento no Educand\u00e1rio Deus e a Natureza A Secretaria de Governo de Indaiatuba, por meio do Sebrae aqui e do Senac, abre as inscri\u00e7\u00f5es para o curso \u201cAprenda a vender material de constru\u00e7\u00e3o\u201d. As aulas acontecer\u00e3o de forma presencial e gratuita, no Educand\u00e1rio Deus e a Natureza, do dia 4 [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":1401,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[193],"tags":[207],"class_list":["post-1400","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacao","tag-indaiatuba"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/posts\/1400","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/comments?post=1400"}],"version-history":[{"count":1,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/posts\/1400\/revisions"}],"predecessor-version":[{"id":1402,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/posts\/1400\/revisions\/1402"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/media\/1401"}],"wp:attachment":[{"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/media?parent=1400"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/categories?post=1400"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/tags?post=1400"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}