{"id":15956,"date":"2023-07-20T07:02:58","date_gmt":"2023-07-20T10:02:58","guid":{"rendered":"https:\/\/imais.online\/portal\/?p=15956"},"modified":"2023-07-20T07:03:00","modified_gmt":"2023-07-20T10:03:00","slug":"operacao-da-policia-civil-de-indaiatuba-prende-dois-suspeitos-de-furtos-e-roubos-a-residencias","status":"publish","type":"post","link":"https:\/\/imais.online\/portal\/operacao-da-policia-civil-de-indaiatuba-prende-dois-suspeitos-de-furtos-e-roubos-a-residencias\/","title":{"rendered":"Opera\u00e7\u00e3o da Pol\u00edcia Civil de Indaiatuba prende dois suspeitos de furtos e roubos a resid\u00eancias"},"content":{"rendered":"<div id=\"imais-3577805935\" class=\"imais-before-content-placement imais-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8787528412751566\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8787528412751566\" \ndata-ad-slot=\"\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>\n<p class=\"has-text-align-right\"><strong>Por g1 Campinas e Regi\u00e3o<\/strong><\/p>\n\n\n\n<p>De acordo com a pol\u00edcia, homens agiam em Indaiatuba, Salto e Itupeva. Um terceiro suspeito foi detido e liberado, sendo que todos t\u00eam passagem por crimes contra o patrim\u00f4nio.<\/p>\n\n\n\n<p>A Pol\u00edcia Civil realizou na manh\u00e3 desta quarta-feira (19) uma opera\u00e7\u00e3o contra um grupo suspeito de cometer furtos e roubos a resid\u00eancias.&nbsp;Dois homens foram presos e um terceiro \u00e9 investigado.<\/p>\n\n\n\n<p>De acordo com o delegado Danilo Am\u00e2ncio Leme, titular de&nbsp;<a class=\"\" href=\"https:\/\/g1.globo.com\/sp\/campinas-regiao\/cidade\/indaiatuba\/\">Indaiatuba<\/a>, os tr\u00eas t\u00eam passagem por crimes contra o patrim\u00f4nio. Um deles era propriet\u00e1rio do carro usado nas a\u00e7\u00f5es.<\/p>\n\n\n\n<p>Ao menos cinco casos ocorreram na pr\u00f3pria cidade, mas tamb\u00e9m s\u00e3o apurados crimes em munic\u00edpios pr\u00f3ximos, como&nbsp;<a class=\"\" href=\"https:\/\/g1.globo.com\/sp\/sorocaba-jundiai\/cidade\/salto\/\">Salto<\/a>&nbsp;e&nbsp;<a class=\"\" href=\"https:\/\/g1.globo.com\/sp\/sorocaba-jundiai\/cidade\/itupeva\/\">Itupeva<\/a>.<\/p>\n\n\n\n<p>&#8220;A investiga\u00e7\u00e3o come\u00e7ou j\u00e1 tem, pelo menos, cinco ou seis meses. \u00c9 um bando criminoso que j\u00e1 estava sendo investigado. Eles come\u00e7aram com furto, principalmente resid\u00eancia&#8221;, disse o delegado.<\/p>\n\n\n\n<p>Embora a maior parte dos roubos e furtos envolvessem resid\u00eancias, o delegado afirma que uma casa de repouso e o Moteiro Itaici tamb\u00e9m foram alvo de criminosos.<\/p>\n\n\n\n<p>Durante a opera\u00e7\u00e3o tamb\u00e9m foram cumpridos cinco mandados de busca e apreens\u00e3o domiciliar, o que resultou na apreens\u00e3o de perfumes, roupas, rel\u00f3gios, celulares e televisores.<\/p>\n\n\n\n<p>Dos tr\u00eas detidos, dois ficaram presos. O terceiro foi levado para a delegacia e liberado. Outros dois suspeitos tamb\u00e9m tiveram a casa averiguada, mas nada foi encontrado.<\/p>\n\n\n\n<p>&#8220;Com esses objetos apreendidos, se aparecer mais v\u00edtimas, vamos ter essa dimens\u00e3o. Mas, com certeza, era um bando acostumado a cometer esse tipo de delito&#8221;, pontuou o delegado.<\/p>\n\n\n\n<p>A a\u00e7\u00e3o teve apoio do Grupo de A\u00e7\u00f5es Especiais (GOE) e da Guarda Civil Municipal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por g1 Campinas e Regi\u00e3o De acordo com a pol\u00edcia, homens agiam em Indaiatuba, Salto e Itupeva. Um terceiro suspeito foi detido e liberado, sendo que todos t\u00eam passagem por crimes contra o patrim\u00f4nio. A Pol\u00edcia Civil realizou na manh\u00e3 desta quarta-feira (19) uma opera\u00e7\u00e3o contra um grupo suspeito de cometer furtos e roubos a [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":15957,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[188],"tags":[73],"class_list":["post-15956","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-indaiatuba","tag-featured"],"_links":{"self":[{"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/posts\/15956","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/comments?post=15956"}],"version-history":[{"count":1,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/posts\/15956\/revisions"}],"predecessor-version":[{"id":15958,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/posts\/15956\/revisions\/15958"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/media\/15957"}],"wp:attachment":[{"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/media?parent=15956"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/categories?post=15956"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/tags?post=15956"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}