{"id":15993,"date":"2023-07-20T18:07:15","date_gmt":"2023-07-20T21:07:15","guid":{"rendered":"https:\/\/imais.online\/portal\/?p=15993"},"modified":"2023-07-20T18:07:17","modified_gmt":"2023-07-20T21:07:17","slug":"expediente-na-prefeitura-inicia-as-12h-nos-dias-de-jogos-da-selecao-feminina-de-futebol","status":"publish","type":"post","link":"https:\/\/imais.online\/portal\/expediente-na-prefeitura-inicia-as-12h-nos-dias-de-jogos-da-selecao-feminina-de-futebol\/","title":{"rendered":"Expediente na Prefeitura inicia \u00e0s 12h nos dias de jogos da sele\u00e7\u00e3o feminina de futebol"},"content":{"rendered":"<div id=\"imais-2497796192\" class=\"imais-before-content-placement imais-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8787528412751566\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8787528412751566\" \ndata-ad-slot=\"\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>\n<p class=\"has-text-align-center\"><em>Hor\u00e1rio vale para todas as reparti\u00e7\u00f5es p\u00fablicas municipais e servi\u00e7os essenciais ter\u00e3o plant\u00e3o<\/em><\/p>\n\n\n\n<p>A Administra\u00e7\u00e3o Municipal informa que haver\u00e1 mudan\u00e7a no hor\u00e1rio do expediente das reparti\u00e7\u00f5es p\u00fablicas municipais durante os jogos da sele\u00e7\u00e3o brasileira de futebol na Copa do Mundo Feminina da Fifa 2023. O expediente ter\u00e1 in\u00edcio \u00e0s 12h nos dias em que a sele\u00e7\u00e3o jogar. Os servi\u00e7os essenciais funcionar\u00e3o em sistema de plant\u00e3o. O Decreto n\u00ba 14.937 que trata do ponto facultativo foi publicado na Imprensa Oficial do Munic\u00edpio desta quinta-feira (20\/7).<\/p>\n\n\n\n<p>A Copa do Mundo Feminina da Fifa acontecer\u00e1 de 20 de julho a 20 de agosto, com sede na Austr\u00e1lia e Nova Zel\u00e2ndia, e o primeiro jogo do Brasil ser\u00e1 realizado na pr\u00f3xima segunda-feira (24\/7), \u00e0s 8h no hor\u00e1rio de Bras\u00edlia, contra o Panam\u00e1. &nbsp;<\/p>\n\n\n\n<p>O formato da competi\u00e7\u00e3o ser\u00e1 igual ao do torneio masculino, com oito grupos de quatro pa\u00edses, em que os dois primeiros se classificam para as pr\u00f3ximas fases, de \u201cmata-mata\u201d. O Brasil est\u00e1 no grupo F. Nesta primeira fase, a sele\u00e7\u00e3o tamb\u00e9m jogar\u00e1 no dia 29 de julho contra a Fran\u00e7a e no dia 2 de agosto contra a Jamaica. Caso ao Brasil se classifique para as pr\u00f3ximas etapas, a suspens\u00e3o do expediente at\u00e9 12h permanecer\u00e1 vigente nos dias dos jogos.<\/p>\n\n\n\n<p>De acordo com o Decreto, as secretarias municipais de Sa\u00fade, Obras e Vias P\u00fablicas, Servi\u00e7os Urbanos e Meio ambiente, Assist\u00eancia Social e o Servi\u00e7o Aut\u00f4nomo de \u00c1gua e Esgotos (Saae), \u00f3rg\u00e3os de fiscaliza\u00e7\u00e3o e os setores ou servi\u00e7os considerados essenciais ao atendimento da popula\u00e7\u00e3o, dever\u00e3o funcionar no per\u00edodo, em sistema de plant\u00e3o.<\/p>\n\n\n\n<p>No dia 18 de julho, o Governo Federal, por meio do Minist\u00e9rio da Gest\u00e3o e da Inova\u00e7\u00e3o em Servi\u00e7os P\u00fablicos, publicou a Portaria 3.814\/2023, estabelecendo ponto facultativo nas reparti\u00e7\u00f5es p\u00fablicas federais em dias que o Brasil entrar\u00e1 em campo. Esta \u00e9 a primeira vez que o ponto facultativo ser\u00e1 implementado durante a competi\u00e7\u00e3o feminina. At\u00e9 ent\u00e3o, essa pr\u00e1tica era adotada no pa\u00eds apenas em dias de jogos da sele\u00e7\u00e3o masculina.<\/p>\n\n\n\n<p><strong>Servi\u00e7os essenciais<\/strong><\/p>\n\n\n\n<p>Na Secretaria Municipal de Sa\u00fade o plant\u00e3o funcionar\u00e1 para urg\u00eancia e emerg\u00eancia na UPA-24h (Unidade de Pronto Atendimento) e no Haoc (Hospital Augusto de Oliveira Camargo). O expediente nas demais unidades de sa\u00fade ter\u00e3o in\u00edcio \u00e0s 12h. O servi\u00e7o de Telemedicina n\u00e3o funcionar\u00e1 no per\u00edodo. O plant\u00e3o odontol\u00f3gico, que tamb\u00e9m \u00e9 realizado na UPA, estar\u00e1 dispon\u00edvel das 7h \u00e0s 19h.<\/p>\n\n\n\n<p>Tamb\u00e9m seguindo o Decreto n\u00ba 14.937\/2023, as unidades escolares da Secretaria Municipal da Educa\u00e7\u00e3o ter\u00e3o as aulas suspensas no per\u00edodo da manh\u00e3 nos dias 24 de julho e 2 de agosto, quando acontecem os jogos da sele\u00e7\u00e3o feminina. J\u00e1 as aulas do per\u00edodo da tarde acontecer\u00e3o normalmente. Nas escolas de per\u00edodo integral e creches o atendimento dos alunos ser\u00e1 iniciado \u00e0s 12h.<\/p>\n\n\n\n<p>Na Secretaria de Servi\u00e7os Urbanos e Meio Ambiente a limpeza urbana e coleta de lixo ser\u00e3o mantidas, normalmente. Os Ecopontos do Jardim Jo\u00e3o Pioli, Jardim Eldorado, Jardim Olinda e Jardim Nova Veneza, permanecem abertos diariamente, das 7h \u00e0s 19h. As feiras livres manter\u00e3o o cronograma habitual. &nbsp;<\/p>\n\n\n\n<p>As equipes de plant\u00e3o do Servi\u00e7o Aut\u00f4nomo de \u00c1gua e Esgoto (Saae) far\u00e3o o atendimento emergencial da popula\u00e7\u00e3o pelo telefone 0800-7722195. A Secretaria de Obras e Vias P\u00fablicas manter\u00e1 de plant\u00e3o as equipes de el\u00e9trica e tr\u00e2nsito. O telefone da Guarda para emerg\u00eancia \u00e9 153, da Pol\u00edcia Militar \u00e9 190, do Corpo de Bombeiros, 193 e da Central de Ambul\u00e2ncias 192.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hor\u00e1rio vale para todas as reparti\u00e7\u00f5es p\u00fablicas municipais e servi\u00e7os essenciais ter\u00e3o plant\u00e3o A Administra\u00e7\u00e3o Municipal informa que haver\u00e1 mudan\u00e7a no hor\u00e1rio do expediente das reparti\u00e7\u00f5es p\u00fablicas municipais durante os jogos da sele\u00e7\u00e3o brasileira de futebol na Copa do Mundo Feminina da Fifa 2023. O expediente ter\u00e1 in\u00edcio \u00e0s 12h nos dias em que a [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":15994,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[188],"tags":[],"class_list":["post-15993","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-indaiatuba"],"_links":{"self":[{"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/posts\/15993","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/comments?post=15993"}],"version-history":[{"count":1,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/posts\/15993\/revisions"}],"predecessor-version":[{"id":15995,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/posts\/15993\/revisions\/15995"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/media\/15994"}],"wp:attachment":[{"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/media?parent=15993"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/categories?post=15993"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/tags?post=15993"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}