{"id":1867,"date":"2021-09-27T15:19:30","date_gmt":"2021-09-27T18:19:30","guid":{"rendered":"https:\/\/imais.online\/portal\/?p=1867"},"modified":"2021-09-27T15:19:38","modified_gmt":"2021-09-27T18:19:38","slug":"senac-abre-inscricoes-para-curso-on-line-voltado-para-redes-sociais","status":"publish","type":"post","link":"https:\/\/imais.online\/portal\/senac-abre-inscricoes-para-curso-on-line-voltado-para-redes-sociais\/","title":{"rendered":"Senac abre inscri\u00e7\u00f5es para curso On-line voltado para redes sociais"},"content":{"rendered":"<div class=\"imais-before-content-placement\" id=\"imais-338576371\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8787528412751566\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8787528412751566\" \ndata-ad-slot=\"\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>\n<p>A Secretaria de Governo de Indaiatuba, por meio do Sebrae Aqui e em parceria com o Senac, abre inscri\u00e7\u00f5es para o curso On-line e gratuito \u201cCria\u00e7\u00e3o de posts para redes sociais\u201d. As aulas acontecer\u00e3o de segunda a sexta-feira, de 18 a 25 de outubro das 18h \u00e0s 22h. Ser\u00e3o disponibilizadas 30 vagas.<\/p>\n\n\n\n<p>O objetivo \u00e9 preparar o aluno para desenvolver solu\u00e7\u00f5es gr\u00e1ficas e textos para a cria\u00e7\u00e3o de posts em redes sociais de forma que ele possa criar e produzir imagens, v\u00eddeos e textos adequando-os \u00e0s caracter\u00edsticas das plataformas escolhidas.<\/p>\n\n\n\n<p>As inscri\u00e7\u00f5es devem ser realizadas no link: https:\/\/www.sympla.com.br\/criacao-de-posts-para-redes-sociais&#8212;senacsebrae&#8212;3302__1355171. O curso \u00e9 destinado para pessoas maiores de 18 anos. A carga hor\u00e1ria total \u00e9 de 24 horas. Mais informa\u00e7\u00f5es, entrar em contato pelo telefone (19) 3834-9272.<\/p>\n\n\n\n<p>Conte\u00fado program\u00e1tico:<\/p>\n\n\n\n<p>\u2022 Redes sociais: conceito.<\/p>\n\n\n\n<p>\u2022 Plataformas de redes sociais: caracter\u00edsticas.<\/p>\n\n\n\n<p>\u2022 T\u00e9cnicas visuais: contraste, simetria e assimetria, simplicidade e complexidade.<\/p>\n\n\n\n<p>\u2022 Cor: aspectos psicol\u00f3gicos.<\/p>\n\n\n\n<p>\u2022 Tipografia: aplica\u00e7\u00f5es e adequa\u00e7\u00f5es.<\/p>\n\n\n\n<p>\u2022 Reda\u00e7\u00e3o para redes sociais: posts, hashtags, tagueamento e links.<\/p>\n\n\n\n<p>\u2022 V\u00eddeo: orienta\u00e7\u00e3o e enquadramentos.<\/p>\n\n\n\n<p>\u2022 Formatos de v\u00eddeo: tamanho e dura\u00e7\u00e3o.<\/p>\n\n\n\n<p>\u2022 Fotografia: orienta\u00e7\u00e3o, propor\u00e7\u00e3o e enquadramento.<\/p>\n\n\n\n<p>SERVI\u00c7O:<\/p>\n\n\n\n<p>DATA: de 18 a 25 de outubro (Segunda a sexta-feira).<\/p>\n\n\n\n<p>HOR\u00c1RIO: das 18h \u00e0s 22h<\/p>\n\n\n\n<p>INSCRI\u00c7\u00d5ES: https:\/\/www.sympla.com.br\/criacao-de-posts-para-redes-sociais&#8212;senacsebrae&#8212;3302__1355171.<\/p>\n\n\n\n<p>TELEFONE: (19) 3834-9272.<\/p>\n\n\n\n<p>Foto: Divulga\u00e7\u00e3o<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Secretaria de Governo de Indaiatuba, por meio do Sebrae Aqui e em parceria com o Senac, abre inscri\u00e7\u00f5es para o curso On-line e gratuito \u201cCria\u00e7\u00e3o de posts para redes sociais\u201d. As aulas acontecer\u00e3o de segunda a sexta-feira, de 18 a 25 de outubro das 18h \u00e0s 22h. Ser\u00e3o disponibilizadas 30 vagas. O objetivo \u00e9 [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":1868,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[188],"tags":[],"class_list":["post-1867","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-indaiatuba"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/posts\/1867","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/comments?post=1867"}],"version-history":[{"count":1,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/posts\/1867\/revisions"}],"predecessor-version":[{"id":1869,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/posts\/1867\/revisions\/1869"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/media\/1868"}],"wp:attachment":[{"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/media?parent=1867"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/categories?post=1867"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/tags?post=1867"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}