{"id":2393,"date":"2021-10-18T15:46:13","date_gmt":"2021-10-18T18:46:13","guid":{"rendered":"https:\/\/imais.online\/portal\/?p=2393"},"modified":"2021-10-18T15:46:15","modified_gmt":"2021-10-18T18:46:15","slug":"saae-recebe-a-visita-do-prefeito-de-louveira","status":"publish","type":"post","link":"https:\/\/imais.online\/portal\/saae-recebe-a-visita-do-prefeito-de-louveira\/","title":{"rendered":"Saae recebe a visita do Prefeito de Louveira"},"content":{"rendered":"<div class=\"imais-before-content-placement\" id=\"imais-47525451\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8787528412751566\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8787528412751566\" \ndata-ad-slot=\"\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>\n<p>O Superintendente do Servi\u00e7o Aut\u00f4nomo de \u00c1gua e Esgotos (Saae), Engenheiro Pedro Claudio Salla, recebeu a visita na sexta-feira (15), do Prefeito de Louveira, Estanislau Steck, acompanhado pela Secretaria de Educa\u00e7\u00e3o, Mara Luciane de Paula, Secret\u00e1ria de Gest\u00e3o Ambiental, Rose Mary S Celidonio, Eng. Agr\u00edcola, Divis\u00e3o de Agricultura, Daniel F Miqueletto, Secret\u00e1rio de Desenvolvimento Econ\u00f4mico, Alessandro Ribeiro Walter e o Secret\u00e1rio de \u00c1gua e Esgoto, Mateus Arantes, Secret\u00e1rio de \u00c1gua e Esgoto.<\/p>\n\n\n\n<p>A proposta do encontro foi de conhecer alguns pontos tur\u00edsticos de Indaiatuba que priorizam o meio ambiente, com conhecimento e a\u00e7\u00f5es, e tamb\u00e9m a troca de experi\u00eancias. A comitiva de Louveira, aproveitou a oportunidade para visitar o Prefeito Nilson Gaspar em seu Gabinete na Prefeitura de Indaiatuba,<\/p>\n\n\n\n<p>O tour teve in\u00edcio no Parque do Mirim, seguiu para o Museu da \u00c1gua e finalizou no Bosque do Saber.<\/p>\n\n\n\n<p>O pessoal de Louveira iniciou o \u201ctour\u201d pelo Parque do Mirim, localizado ao redor da represa do rio Capivari-Mirim e possui uma \u00c1rea de Preserva\u00e7\u00e3o Ambiental para promover a educa\u00e7\u00e3o ambiental e a sensibiliza\u00e7\u00e3o da import\u00e2ncia da preserva\u00e7\u00e3o dos recursos h\u00eddricos e ambientais da regi\u00e3o.<\/p>\n\n\n\n<p>No Parque tamb\u00e9m, eles encontraram muitas atra\u00e7\u00f5es para se divertir e descansar perto da natureza: uma verdadeira \u00e1rea verde em forma\u00e7\u00e3o, com \u00e1rvores nativas plantadas pela popula\u00e7\u00e3o e pelo Saae, deques para pesca, pedalinhos, parquinho, academia para a terceira idade, pista de caminhada, mirante, quadras de v\u00f4lei de areia, futebol society e poliesportiva com vista para represa.<\/p>\n\n\n\n<p>Na sequ\u00eancia, eles foram at\u00e9 o O Museu da \u00c1gua que tem a proposta de ser uma refer\u00eancia em educa\u00e7\u00e3o ambiental, voltada \u00e0 gest\u00e3o de recursos h\u00eddricos. Um espa\u00e7o que alia ci\u00eancia, tecnologia e acervo para contar a hist\u00f3ria da \u00e1gua em Indaiatuba e sua import\u00e2ncia em uma perspectiva universal. Uma nova op\u00e7\u00e3o de lazer para as fam\u00edlias tanto de nossa cidade como para as cidades vizinhas.<\/p>\n\n\n\n<p>O Museu da \u00c1gua conta ainda com a exposi\u00e7\u00e3o \u201cOrigem e Prop\u00f3sitos\u201d, que conduz o visitante a uma incr\u00edvel viagem tecnol\u00f3gica, com realidade virtual, interatividade e holografia.<\/p>\n\n\n\n<p>No Bosque do Saber os visitantes tiveram a oportunidade de conhecer os Projetos ligados a grande curricular do munic\u00edpio e tamb\u00e9m alinhados a BNCC &#8211; Base Nacional Curricular Comum, os quiosques da Leitora e Ecojogos, o Ranchinho Verde, onde tem a sementeira com diversas sementes nativas frutas onde as crian\u00e7as fazem o plantio e tem aula sobre o estudo do meio.<\/p>\n\n\n\n<p>Para o superintendente da Autarquia, a visita foi muito produtiva. \u201cEstou honrado com a presen\u00e7a dos representantes de Louveira, em nossa cidade. Precisamos nos unir e trocar experi\u00eancias visando sempre o bem comum das pessoas e refletir sobre nossas tarefas enquanto cidad\u00e3os e com o apoio da popula\u00e7\u00e3o, por meio de cidad\u00e3os preocupados, que est\u00e3o cumprindo o seu papel de forma virtuosa e entendendo que todos fazemos parte de um coletivo de a\u00e7\u00f5es e todos juntos faremos a diferen\u00e7a sobre as quest\u00f5es ambientais e a qualidade de vida dos mun\u00edcipes\u201d, conclui.<\/p>\n\n\n\n<p>Refer\u00eancia no quesito qualidade de vida, Indaiatuba \u00e9 muito mais do que apenas uma t\u00edpica cidade do interior. A regi\u00e3o se destaca por proporcionar, com efic\u00e1cia, lazer, servi\u00e7os e infraestrutura aos seus habitantes.<\/p>\n\n\n\n<p>Indaiatuba foi eleita uma das cidades mais conectadas do Brasil, reflexo da integra\u00e7\u00e3o entre mobilidade, urbanismo, meio ambiente, energia etc. Tamb\u00e9m \u00e9 considerada uma cidade inteligente, pois oferece sistemas digitais de comunica\u00e7\u00e3o em diversos setores, como sa\u00fade e educa\u00e7\u00e3o. Al\u00e9m disso, a cidade disp\u00f5e de uma ampla cobertura virtual, contando com rede wi-fi gratuita em pontos de \u00f4nibus e outros locais p\u00fablicos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Superintendente do Servi\u00e7o Aut\u00f4nomo de \u00c1gua e Esgotos (Saae), Engenheiro Pedro Claudio Salla, recebeu a visita na sexta-feira (15), do Prefeito de Louveira, Estanislau Steck, acompanhado pela Secretaria de Educa\u00e7\u00e3o, Mara Luciane de Paula, Secret\u00e1ria de Gest\u00e3o Ambiental, Rose Mary S Celidonio, Eng. Agr\u00edcola, Divis\u00e3o de Agricultura, Daniel F Miqueletto, Secret\u00e1rio de Desenvolvimento Econ\u00f4mico, [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":2394,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[188],"tags":[],"class_list":["post-2393","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-indaiatuba"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/posts\/2393","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/comments?post=2393"}],"version-history":[{"count":1,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/posts\/2393\/revisions"}],"predecessor-version":[{"id":2395,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/posts\/2393\/revisions\/2395"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/media\/2394"}],"wp:attachment":[{"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/media?parent=2393"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/categories?post=2393"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/tags?post=2393"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}