{"id":2474,"date":"2021-10-20T10:51:12","date_gmt":"2021-10-20T13:51:12","guid":{"rendered":"https:\/\/imais.online\/portal\/?p=2474"},"modified":"2021-10-20T10:51:17","modified_gmt":"2021-10-20T13:51:17","slug":"cpi-da-covid-veja-a-versao-final-do-relatorio-que-sera-lido-nesta-quarta","status":"publish","type":"post","link":"https:\/\/imais.online\/portal\/cpi-da-covid-veja-a-versao-final-do-relatorio-que-sera-lido-nesta-quarta\/","title":{"rendered":"CPI da Covid: veja a vers\u00e3o final do relat\u00f3rio que ser\u00e1 lido nesta quarta"},"content":{"rendered":"<div class=\"imais-before-content-placement\" id=\"imais-2671511837\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8787528412751566\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8787528412751566\" \ndata-ad-slot=\"\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>\n<h2 class=\"has-text-align-center wp-block-heading\">Com 1.180 p\u00e1ginas e pedido de indiciamento de 66 pessoas e duas empresas, o documento ser\u00e1 votado na pr\u00f3xima semana<\/h2>\n\n\n\n<p>\u00c0s 10h desta quarta-feira (20), a Comiss\u00e3o Parlamentar de Inqu\u00e9rito (CPI) da Covid-19 se re\u00fane para fazer a leitura do relat\u00f3rio final. O documento \u00e9 o compilado de tudo que foi apurado nos quase seis meses de reuni\u00f5es, desde a abertura, em 27 de abril deste ano. Nele tamb\u00e9m est\u00e3o sugest\u00f5es de indiciamentos e pedidos de investiga\u00e7\u00f5es. A partir do relat\u00f3rio, \u00f3rg\u00e3os fiscalizadores ser\u00e3o acionados para darem continuidade \u00e0s investiga\u00e7\u00f5es.&nbsp;<\/p>\n\n\n\n<p>O documento, elaborado pelo relator Renan Calheiros (MDB-AL), tem 1.180 p\u00e1ginas e pedido de indiciamento para 66 pessoas e duas empresas. Foi alterado ap\u00f3s uma reuni\u00e3o de Calheiros com outros integrantes da comiss\u00e3o, na noite de ter\u00e7a-feira (19)<\/p>\n\n\n\n<p>No documento finalizado, Calheiros&nbsp;<a href=\"https:\/\/noticias.r7.com\/brasilia\/cupula-da-cpi-decide-tirar-genocidio-do-relatorio-final-19102021\">retirou o pedido de indiciamento do presidente Jair Bolsonaro pelo crime de genoc\u00eddio contra povos ind\u00edgenas.<\/a>&nbsp;A proposta chegou a ser inclu\u00edda em uma pr\u00e9via do relat\u00f3rio, mas n\u00e3o houve consenso entre os senadores. Em reuni\u00e3o na noite de ter\u00e7a-feira (19), o G7, grupo majorit\u00e1rio da CPI, decidiu retirar a indica\u00e7\u00e3o do crime. Tamb\u00e9m foi desconsiderado o pedido de indiciamento de advocacia administrativa contra o senador Fl\u00e1vio Bolsonaro (Patriota-RJ).<\/p>\n\n\n\n<p>As mudan\u00e7as no relat\u00f3rio ocorreram depois que a minuta do documento vazou antes de ser lida por todos os integrantes do G7. O vazamento gerou profundos desgastes com cr\u00edticas contundentes do presidente da CPI, Omar Aziz (PSD-AM), ao relator, Renan Calheiros.<\/p>\n\n\n\n<p>Se antes o texto previa um cap\u00edtulo inteiro para descrever o crime de genoc\u00eddio no direito brasileiro, o nome mal aparece na vers\u00e3o final.\u00a0<br><br>O nome do vereador do Rio de Janeiro Carlos Bolsonaro (Republicanos), filho do presidente, continua do documento e \u00e9 inclu\u00eddo no trecho que trata de\u00a0<em>fake news<\/em>\u00a0durante a pandemia. Os senadores retiraram imputa\u00e7\u00f5es \u00e0 empresa Belcher Farmac\u00eautica, que possui rela\u00e7\u00e3o com o deputado Ricardo Barros (PP-PR), ao pastor Silas Malafaia, ao secret\u00e1rio de Sa\u00fade Ind\u00edgena Robson Santos da Silva, ao presidente da Funai, Marcelo Augusto Xavier, e ao s\u00f3cio da Belcher Farmac\u00eautica\u00a0Emanuel Catori.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.r7.com\/r7\/media\/pdf\/CPI%20Covid%20-RelatorioFinal.pdf\"><strong>Veja a vers\u00e3o final do documento aqui.\u00a0<\/strong><\/a><\/p>\n\n\n\n<p>Isabella Macedo, Sarah Te\u00f3filo e Kelly Almeida, do R7<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Com 1.180 p\u00e1ginas e pedido de indiciamento de 66 pessoas e duas empresas, o documento ser\u00e1 votado na pr\u00f3xima semana \u00c0s 10h desta quarta-feira (20), a Comiss\u00e3o Parlamentar de Inqu\u00e9rito (CPI) da Covid-19 se re\u00fane para fazer a leitura do relat\u00f3rio final. O documento \u00e9 o compilado de tudo que foi apurado nos quase seis [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":2475,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[189],"tags":[],"class_list":["post-2474","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/posts\/2474","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/comments?post=2474"}],"version-history":[{"count":1,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/posts\/2474\/revisions"}],"predecessor-version":[{"id":2476,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/posts\/2474\/revisions\/2476"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/media\/2475"}],"wp:attachment":[{"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/media?parent=2474"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/categories?post=2474"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/tags?post=2474"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}