{"id":25325,"date":"2025-01-07T09:05:10","date_gmt":"2025-01-07T12:05:10","guid":{"rendered":"https:\/\/imais.online\/portal\/?p=25325"},"modified":"2025-01-07T09:05:11","modified_gmt":"2025-01-07T12:05:11","slug":"prefeito-dr-custodio-anuncia-acoes-para-combate-do-uso-e-comercializacao-de-cerol","status":"publish","type":"post","link":"https:\/\/imais.online\/portal\/prefeito-dr-custodio-anuncia-acoes-para-combate-do-uso-e-comercializacao-de-cerol\/","title":{"rendered":"Prefeito Dr. Cust\u00f3dio anuncia a\u00e7\u00f5es para combate do uso e comercializa\u00e7\u00e3o de cerol"},"content":{"rendered":"<div id=\"imais-594234608\" class=\"imais-before-content-placement imais-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8787528412751566\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8787528412751566\" \ndata-ad-slot=\"\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>\n<p class=\"has-text-align-center\"><em>Determina\u00e7\u00f5es visam promover a seguran\u00e7a e preservar a vida da popula\u00e7\u00e3o<\/em><\/p>\n\n\n\n<p>Na manh\u00e3 desta segunda-feira (6\/1), o prefeito de Indaiatuba, Dr. Cust\u00f3dio Tavares, reuniu em seu Gabinete uma frente de trabalho para definir a\u00e7\u00f5es imediatas para preven\u00e7\u00e3o e o combate ao uso e comercializa\u00e7\u00e3o de cerol. Ficou definido que a partir de hoje at\u00e9 o fim de janeiro, quando acaba o per\u00edodo de f\u00e9rias escolares, haver\u00e1 fiscaliza\u00e7\u00e3o intensificada e di\u00e1ria, com execu\u00e7\u00e3o das multas previstas em legisla\u00e7\u00e3o municipal, para coibir o uso e comercializa\u00e7\u00e3o de linhas cortantes. &nbsp;Uma campanha publicit\u00e1ria enfatizando o risco, informando que a pr\u00e1tica \u00e9 crime e incentivando o uso da antena em motos e a den\u00fancia para \u00f3rg\u00e3os competentes entrar\u00e1 em vigor esta semana. Palestras educativas em escolas e igrejas ser\u00e3o realizadas entre os meses de fevereiro a junho.<\/p>\n\n\n\n<p>A a\u00e7\u00e3o tra\u00e7ada visa promover a seguran\u00e7a e preservar a vida da popula\u00e7\u00e3o. \u201cNesta reuni\u00e3o de hoje ficou determinada a amplia\u00e7\u00e3o das a\u00e7\u00f5es de preven\u00e7\u00e3o e combate ao uso de cerol. As leis ser\u00e3o respeitadas para que possamos combater esse tipo de crime, que ceifa vidas e \u00e9 uma preocupa\u00e7\u00e3o muito grande tanto para o poder p\u00fablico quanto para os mun\u00edcipes\u201d, declarou Dr. Cust\u00f3dio.<\/p>\n\n\n\n<p>A cidade possui legisla\u00e7\u00e3o espec\u00edfica contra o uso e venda de cerol e linha chilena, com multas de 50 Ufesps (R$ 1.851,00) para a utiliza\u00e7\u00e3o;&nbsp; 300 Ufesps (R$ 11.106,00) e cassa\u00e7\u00e3o de alvar\u00e1 para o com\u00e9rcio. Os valores podem dobrar em caso de reincid\u00eancia. De 2022 a 2024 foram aplicadas 23 multas com o valor montante de R$ 38.236,00.<\/p>\n\n\n\n<p>Participaram da reuni\u00e3o o secret\u00e1rio de Seguran\u00e7a P\u00fablica, Sandro Bezerra Lima, a chefe de Gabinete Institucional, Graziela Garcia, o secret\u00e1rio adjunto de Comunica\u00e7\u00e3o, Lincoln Franco, o diretor da Guarda Civil, Edson Massaioli, o diretor do departamento de Fiscaliza\u00e7\u00e3o, Taxas e Posturas, Rog\u00e9rio Giora e o agente da Defesa Civil,&nbsp;Djansen Rodrigu\u00eas. O presidente Murilo Celso Oliveira, vice-presidente, Ricardo Cruz e Silva e o conselheiro Eli Jonathan Nunes de Andrade da Silva, da AMMEI (Associa\u00e7\u00e3o dos Motoboys, Motofretistas e Entregadores de Indaiatuba) tamb\u00e9m estiveram presentes para trazer sugest\u00f5es e firmar uma parceria para ajudar na conscientiza\u00e7\u00e3o do uso da antena na moto e colaborar nas den\u00fancias de pessoas soltando pipas, j\u00e1 que estes trabalhadores est\u00e3o rodando diariamente em todo o munic\u00edpio.<\/p>\n\n\n\n<p><strong>Apreens\u00f5es<\/strong><\/p>\n\n\n\n<p>A Guarda Civil de Indaiatuba apreendeu 491 itens de insumos para fabrica\u00e7\u00e3o de linha cortante, linhas prontas para venda e fogos de artif\u00edcio em um com\u00e9rcio na Rua dos Indai\u00e1s. A opera\u00e7\u00e3o foi realizada na manh\u00e3 do domingo (5\/1), ap\u00f3s uma den\u00fancia e contou com o apoio do departamento de Fiscaliza\u00e7\u00e3o, Taxas e Posturas. O respons\u00e1vel pelo com\u00e9rcio e um funcion\u00e1rio foram detidos e encaminhados \u00e0 Delegacia de Pol\u00edcia, onde foi registrado o boletim de ocorr\u00eancia. O estabelecimento comercial foi autuado em 600 Ufesps (R$ 22.212,00), pois \u00e9 reincidente, e foi aberto um processo administrativo para a poss\u00edvel cassa\u00e7\u00e3o do alvar\u00e1.<\/p>\n\n\n\n<p>A a\u00e7\u00e3o de fiscaliza\u00e7\u00e3o continuou no per\u00edodo da tarde pelos bairros Jardins Paulistano, Paulista, Bom Sucesso, Colibris, Campo Bonito, Morada do Sol e seguir\u00e1 todos os dias, at\u00e9 o final de janeiro, em todas as \u00e1reas da cidade.<\/p>\n\n\n\n<p><strong>Den\u00fancias<\/strong><\/p>\n\n\n\n<p>Den\u00fancias sobre venda, uso e fabrica\u00e7\u00e3o da linha cortante podem ser feitas pelo 153 da Guarda Civil.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Determina\u00e7\u00f5es visam promover a seguran\u00e7a e preservar a vida da popula\u00e7\u00e3o Na manh\u00e3 desta segunda-feira (6\/1), o prefeito de Indaiatuba, Dr. Cust\u00f3dio Tavares, reuniu em seu Gabinete uma frente de trabalho para definir a\u00e7\u00f5es imediatas para preven\u00e7\u00e3o e o combate ao uso e comercializa\u00e7\u00e3o de cerol. Ficou definido que a partir de hoje at\u00e9 o [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":25326,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[188],"tags":[73],"class_list":["post-25325","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-indaiatuba","tag-featured"],"_links":{"self":[{"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/posts\/25325","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/comments?post=25325"}],"version-history":[{"count":1,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/posts\/25325\/revisions"}],"predecessor-version":[{"id":25327,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/posts\/25325\/revisions\/25327"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/media\/25326"}],"wp:attachment":[{"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/media?parent=25325"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/categories?post=25325"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/tags?post=25325"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}