{"id":2542,"date":"2021-10-22T11:07:14","date_gmt":"2021-10-22T14:07:14","guid":{"rendered":"https:\/\/imais.online\/portal\/?p=2542"},"modified":"2021-10-22T11:07:15","modified_gmt":"2021-10-22T14:07:15","slug":"prefeitura-de-indaiatuba-e-saae-estao-em-fase-de-elaboracao-do-novo-plano-municipal-do-saneamento-basico","status":"publish","type":"post","link":"https:\/\/imais.online\/portal\/prefeitura-de-indaiatuba-e-saae-estao-em-fase-de-elaboracao-do-novo-plano-municipal-do-saneamento-basico\/","title":{"rendered":"Prefeitura de Indaiatuba e Saae est\u00e3o em fase de elabora\u00e7\u00e3o do novo Plano Municipal do Saneamento B\u00e1sico"},"content":{"rendered":"<div class=\"imais-before-content-placement\" id=\"imais-603109974\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8787528412751566\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8787528412751566\" \ndata-ad-slot=\"\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>\n<p>A Prefeitura de Indaiatuba iniciou no dia 27 de agosto de 2021 a revis\u00e3o do Plano Municipal de Saneamento B\u00e1sico (PMSB), atrav\u00e9s da contrata\u00e7\u00e3o de empresa especializada na \u00e1rea do saneamento. O objetivo principal da revis\u00e3o Plano Municipal de Saneamento \u00e9 universaliza\u00e7\u00e3o dos servi\u00e7os no munic\u00edpio, tendo como metas melhorar a sa\u00fade e qualidade de vida de todos por meio do saneamento b\u00e1sico.<\/p>\n\n\n\n<p>Para elaborar um diagn\u00f3stico da situa\u00e7\u00e3o do saneamento no munic\u00edpio de Indaiatuba, h\u00e1 necessidade de tamb\u00e9m escutar as dores da popula\u00e7\u00e3o. Assim, torna-se necess\u00e1rio que haja plena participa\u00e7\u00e3o dos moradores de Indaiatuba na elabora\u00e7\u00e3o do referido PMSB. O question\u00e1rio est\u00e1 dispon\u00edvel no site: www.saneamentoindaiatuba.com.br para que seja poss\u00edvel a participa\u00e7\u00e3o e colabora\u00e7\u00e3o de todos na elabora\u00e7\u00e3o deste trabalho.<\/p>\n\n\n\n<p>Essa evolu\u00e7\u00e3o na \u00e1rea do saneamento na cidade j\u00e1 vem ocorrendo por meio de grandes investimentos realizados, como por exemplo a inaugura\u00e7\u00e3o da Barragem do Rio Capivari-Mirim no fim do ano de 2018 e a finaliza\u00e7\u00e3o das amplia\u00e7\u00f5es da Esta\u00e7\u00e3o de Tratamento de Esgoto (ETE) M\u00e1rio Araldo Candello no ano de 2020, permitindo que o munic\u00edpio realizasse o tratamento de 100% dos esgotos coletados.<\/p>\n\n\n\n<p>Os n\u00fameros do Sistema Nacional de Informa\u00e7\u00f5es sobre Saneamento (SNIS) apontam que, somente em 2019 a n\u00edvel nacional, a coleta de esgoto chegou a 61% da popula\u00e7\u00e3o, mas apenas 49% dos esgotos gerados no pais s\u00e3o tratados. A melhor situa\u00e7\u00e3o est\u00e1 no atendimento de \u00e1gua tratada, que chega a 92% dos brasileiros em \u00e1reas urbanas. Em Indaiatuba, 98% da popula\u00e7\u00e3o \u00e9 atendido com \u00e1gua tratada e quanto ao esgoto, 70% do volume coletado \u00e9 tratado. \u00cdndices que vem crescendo com investimentos e cuidado com o bem-estar da popula\u00e7\u00e3o.<\/p>\n\n\n\n<p>A Lei 11.445 de 2007 trouxe novas diretrizes nacionais, definiu o planejamento dos servi\u00e7os b\u00e1sicos como instrumento fundamental para se alcan\u00e7ar o acesso universal do saneamento b\u00e1sico e entre essas ferramentas criou o Plano Municipal de Saneamento B\u00e1sico (PMSB). O plano deve ser elaborado pelas Prefeituras e devidamente transformado em legisla\u00e7\u00e3o municipal, sendo essencial para obten\u00e7\u00e3o de recursos financeiros junto ao Governo Federal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Indaiatuba iniciou no dia 27 de agosto de 2021 a revis\u00e3o do Plano Municipal de Saneamento B\u00e1sico (PMSB), atrav\u00e9s da contrata\u00e7\u00e3o de empresa especializada na \u00e1rea do saneamento. O objetivo principal da revis\u00e3o Plano Municipal de Saneamento \u00e9 universaliza\u00e7\u00e3o dos servi\u00e7os no munic\u00edpio, tendo como metas melhorar a sa\u00fade e qualidade de [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":2543,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[188],"tags":[],"class_list":["post-2542","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-indaiatuba"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/posts\/2542","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/comments?post=2542"}],"version-history":[{"count":1,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/posts\/2542\/revisions"}],"predecessor-version":[{"id":2544,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/posts\/2542\/revisions\/2544"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/media\/2543"}],"wp:attachment":[{"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/media?parent=2542"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/categories?post=2542"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/tags?post=2542"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}