{"id":27902,"date":"2025-07-02T19:31:04","date_gmt":"2025-07-02T22:31:04","guid":{"rendered":"https:\/\/imais.online\/portal\/?p=27902"},"modified":"2025-07-02T19:31:05","modified_gmt":"2025-07-02T22:31:05","slug":"atletas-do-espaco-avancar-participam-das-olimpiadas-especiais-brasil-em-jundiai","status":"publish","type":"post","link":"https:\/\/imais.online\/portal\/atletas-do-espaco-avancar-participam-das-olimpiadas-especiais-brasil-em-jundiai\/","title":{"rendered":"Atletas do Espa\u00e7o Avan\u00e7ar participam das Olimp\u00edadas Especiais Brasil em Jundia\u00ed"},"content":{"rendered":"<div id=\"imais-58117512\" class=\"imais-before-content-placement imais-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8787528412751566\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8787528412751566\" \ndata-ad-slot=\"\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>\n<p class=\"has-text-align-center\"><em><small>&#8220;Programa Atleta Saud\u00e1vel&#8221; contou com a presen\u00e7a de 11 atletas de Indaiatuba com TEA e Defici\u00eancia Intelectual<\/small><\/em><\/p>\n\n\n\n<p>No \u00faltimo s\u00e1bado (28\/6), a equipe do Quebrando Barreiras no Esporte, do Espa\u00e7o Avan\u00e7ar Indaiatuba, participou do evento &#8220;Programa Atleta Saud\u00e1vel&#8221;, realizado na Universidade UNIP\/Jundia\u00ed. As Olimp\u00edadas Especiais Brasil t\u00eam como objetivo do promover a sa\u00fade e o bem-estar de atletas com TEA, defici\u00eancia intelectual e suas fam\u00edlias. Todos os participantes receberam medalhas de participa\u00e7\u00e3o, simbolizando o esfor\u00e7o e a dedica\u00e7\u00e3o de cada um deles. As fam\u00edlias tiveram a oportunidade de acompanhar de perto as atividades, j\u00e1 que elas participaram do F\u00f3rum de Fam\u00edlias, promovendo a integra\u00e7\u00e3o e o apoio entre todos os presentes.<\/p>\n\n\n\n<p>Os jogos e brincadeiras marcaram presen\u00e7a na programa\u00e7\u00e3o, animando os participantes e criando um ambiente festivo. O evento tamb\u00e9m contou com apresenta\u00e7\u00f5es de gin\u00e1stica r\u00edtmica e capoeira, finalizando com o emocionante juramento dos atletas ao som do Hino Nacional. Sob lideran\u00e7a do professor de esporte adaptado, Alexandre Ferreira de Souza, os 11 atletas de Indaiatuba com Transtorno do Espectro Autista (TEA) e Defici\u00eancia Intelectual que representaram a cidade foram: Allan Rocha Neves, Bryan Rodrigues, Gabriel Moreira, Juliane Dos Santos, Jo\u00e3o Pedro Le\u00e3o, Lorrainy Michele, Antonio Garbin, Wesley Uva Carvalho, Vitor Lorenzo de Aguiar, Mariana Carvalho e Miguel Gon\u00e7alves.<\/p>\n\n\n\n<p>Al\u00e9m disso, foram realizadas palestras educativas sobre sa\u00fade e nutri\u00e7\u00e3o, proporcionando aos atletas informa\u00e7\u00f5es valiosas para manter um estilo de vida saud\u00e1vel. O Programa Atleta Saud\u00e1vel n\u00e3o s\u00f3 promove a sa\u00fade e o bem-estar dos atletas, mas tamb\u00e9m fortalece la\u00e7os familiares e comunit\u00e1rios, mostrando que a inclus\u00e3o e a celebra\u00e7\u00e3o da diversidade s\u00e3o fundamentais na constru\u00e7\u00e3o de uma sociedade mais justa e saud\u00e1vel.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Programa Atleta Saud\u00e1vel&#8221; contou com a presen\u00e7a de 11 atletas de Indaiatuba com TEA e Defici\u00eancia Intelectual No \u00faltimo s\u00e1bado (28\/6), a equipe do Quebrando Barreiras no Esporte, do Espa\u00e7o Avan\u00e7ar Indaiatuba, participou do evento &#8220;Programa Atleta Saud\u00e1vel&#8221;, realizado na Universidade UNIP\/Jundia\u00ed. As Olimp\u00edadas Especiais Brasil t\u00eam como objetivo do promover a sa\u00fade e o [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":27903,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[188],"tags":[],"class_list":["post-27902","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-indaiatuba"],"_links":{"self":[{"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/posts\/27902","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/comments?post=27902"}],"version-history":[{"count":1,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/posts\/27902\/revisions"}],"predecessor-version":[{"id":27904,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/posts\/27902\/revisions\/27904"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/media\/27903"}],"wp:attachment":[{"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/media?parent=27902"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/categories?post=27902"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/tags?post=27902"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}