{"id":28041,"date":"2025-07-14T15:12:00","date_gmt":"2025-07-14T18:12:00","guid":{"rendered":"https:\/\/imais.online\/portal\/?p=28041"},"modified":"2025-07-14T15:12:01","modified_gmt":"2025-07-14T18:12:01","slug":"motorista-morre-apos-carro-cair-em-barranco-na-rodovia-santos-dumont","status":"publish","type":"post","link":"https:\/\/imais.online\/portal\/motorista-morre-apos-carro-cair-em-barranco-na-rodovia-santos-dumont\/","title":{"rendered":"Motorista morre ap\u00f3s carro cair em barranco na Rodovia Santos Dumont"},"content":{"rendered":"<div id=\"imais-3392266276\" class=\"imais-before-content-placement imais-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8787528412751566\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8787528412751566\" \ndata-ad-slot=\"\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>\n<p>Um tr\u00e1gico acidente ocorrido na manh\u00e3 desta segunda-feira (14) na Rodovia Santos Dumont (SP-075), em Indaiatuba, resultou na morte de um motorista ainda n\u00e3o identificado. O ve\u00edculo que ele conduzia perdeu o controle e caiu em um barranco, conforme informa\u00e7\u00f5es da Pol\u00edcia Rodovi\u00e1ria.<\/p>\n\n\n\n<p>O incidente aconteceu no sentido Sorocaba da rodovia. De acordo com os relatos, o carro invadiu o canteiro central, colidiu com o barranco de um viaduto e, em seguida, despencou em um c\u00f3rrego. As equipes de resgate que atenderam a ocorr\u00eancia constataram o \u00f3bito do condutor no pr\u00f3prio local do acidente.<\/p>\n\n\n\n<p>A per\u00edcia foi acionada para investigar as causas da perda de controle do ve\u00edculo. At\u00e9 o momento, a identidade da v\u00edtima n\u00e3o foi confirmada, pois o motorista n\u00e3o portava documentos. Apesar da gravidade do acidente, o tr\u00e2nsito na Rodovia Santos Dumont n\u00e3o foi significativamente afetado.<\/p>\n\n\n\n<p>Este lament\u00e1vel epis\u00f3dio refor\u00e7a a import\u00e2ncia da prud\u00eancia e aten\u00e7\u00e3o ao dirigir, especialmente em rodovias de grande fluxo como a Santos Dumont. As autoridades continuam investigando o caso para esclarecer todos os detalhes do ocorrido.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um tr\u00e1gico acidente ocorrido na manh\u00e3 desta segunda-feira (14) na Rodovia Santos Dumont (SP-075), em Indaiatuba, resultou na morte de um motorista ainda n\u00e3o identificado. O ve\u00edculo que ele conduzia perdeu o controle e caiu em um barranco, conforme informa\u00e7\u00f5es da Pol\u00edcia Rodovi\u00e1ria. O incidente aconteceu no sentido Sorocaba da rodovia. De acordo com os [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":28042,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[188],"tags":[],"class_list":["post-28041","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-indaiatuba"],"_links":{"self":[{"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/posts\/28041","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/comments?post=28041"}],"version-history":[{"count":1,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/posts\/28041\/revisions"}],"predecessor-version":[{"id":28043,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/posts\/28041\/revisions\/28043"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/media\/28042"}],"wp:attachment":[{"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/media?parent=28041"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/categories?post=28041"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/tags?post=28041"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}