{"id":2836,"date":"2021-11-05T16:53:43","date_gmt":"2021-11-05T19:53:43","guid":{"rendered":"https:\/\/imais.online\/portal\/?p=2836"},"modified":"2021-11-05T16:53:46","modified_gmt":"2021-11-05T19:53:46","slug":"secretaria-de-educacao-de-indaiatuba-implanta-o-sistema-sesi-de-ensino-na-rede-municipal","status":"publish","type":"post","link":"https:\/\/imais.online\/portal\/secretaria-de-educacao-de-indaiatuba-implanta-o-sistema-sesi-de-ensino-na-rede-municipal\/","title":{"rendered":"Secretaria de Educa\u00e7\u00e3o de Indaiatuba implanta o Sistema Sesi de Ensino na Rede Municipal"},"content":{"rendered":"<div class=\"imais-before-content-placement\" id=\"imais-3519970634\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8787528412751566\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8787528412751566\" \ndata-ad-slot=\"\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>\n<p>A partir de 2022 a Secretaria de Educa\u00e7\u00e3o de Indaiatuba implantar\u00e1 o Sistema Sesi de Ensino para os alunos da Educa\u00e7\u00e3o Infantil (Etapas I e II) e Ensino Fundamental I (1\u00ba ao 5\u00ba ano). Essa \u00e9 mais uma a\u00e7\u00e3o que vem para somar a s\u00e9rie de reformula\u00e7\u00f5es que est\u00e3o sendo implantadas na Rede Municipal de Ensino.<\/p>\n\n\n\n<p>Com investimento de R$ 4.399.704,26 o conv\u00eanio beneficiar\u00e1 mais de 20 mil alunos com o material did\u00e1tico e ainda prev\u00ea 494 horas de capacita\u00e7\u00e3o presencial e on-line para professores, gestores e t\u00e9cnicos das 44 unidades escolares envolvidas na parceria.<\/p>\n\n\n\n<p>O prefeito Nilson Gaspar assinou a parceria na ter\u00e7a-feira, 26 de outubro, durante evento no Centro de Atividades Sesi Antonio Erm\u00edrio de Moraes. \u201cAssinamos uma parceria muito importante, junto ao presidente do Sesi-SP e Fiesp, Paulo Skaf, para aumentar ainda mais a qualidade de educa\u00e7\u00e3o de Indaiatuba, que j\u00e1 \u00e9 refer\u00eancia nacional\u201d, exaltou Gaspar.<\/p>\n\n\n\n<p>O secret\u00e1rio de Educa\u00e7\u00e3o anunciou mais essa novidade que chega para agregar toda uma reformula\u00e7\u00e3o que est\u00e1 acontecendo na Rede Municipal. \u201cA Secretaria de Educa\u00e7\u00e3o continua avan\u00e7ando. Para o ano de 2022, n\u00f3s adquirimos o material did\u00e1tico do Sesi, que ser\u00e1 um grande avan\u00e7o para apoiar o processo de ensino e aprendizagem das nossas crian\u00e7as. Esse \u00e9 mais um degrau que avan\u00e7amos em uma s\u00e9rie de boas not\u00edcias que estamos preparando para a moderniza\u00e7\u00e3o do nosso ensino\u201d, declarou Heleno Luiz Junior.<\/p>\n\n\n\n<p>Kelly An\u00edsia, que \u00e9 professora orientadora pedag\u00f3gica da Secretaria de Educa\u00e7\u00e3o de Indaiatuba, explicou que a escolha do Sistema Sesi de Ensino foi muito bem estudada por toda equipe. \u201cA escolha desse material de ensino passou por uma an\u00e1lise pedag\u00f3gica com crit\u00e9rios que consideraram a rela\u00e7\u00e3o do Sistema Sesi com o curr\u00edculo aplicado pela Rede Municipal de Indaiatuba, portanto ele vem para apoiar os trabalhos que nossos professores j\u00e1 realizam. Esse material tamb\u00e9m est\u00e1 alinhado com os avan\u00e7os tecnol\u00f3gicos que estamos implantando em nossas escolas, al\u00e9m das forma\u00e7\u00f5es e estudos que nossos professores ir\u00e3o receber\u201d, justificou.<\/p>\n\n\n\n<p>Cada aluno, de acordo com o n\u00edvel que estuda, receber\u00e1 no in\u00edcio do ano letivo um kit contendo os seguintes livros did\u00e1ticos: Pr\u00e9-Escola: Movimento do Aprender- Livro Integrado e encartes de apoio; Ensino Fundamental: Movimento do Aprender: Ci\u00eancias da Natureza, Ci\u00eancias Humanas, Matem\u00e1tica, L\u00edngua Portuguesa, Saiba Mais, Muitos Textos \u2026 Tantas Palavras e encartes para a Disciplina de Arte.<\/p>\n\n\n\n<p>Os alunos de 1\u00ba e 2\u00ba anos tamb\u00e9m ir\u00e3o receber um material de apoio para a alfabetiza\u00e7\u00e3o. J\u00e1 os professores receber\u00e3o o Livro do Professor com orienta\u00e7\u00f5es did\u00e1ticas para a pr\u00e1tica em sala de aula.<\/p>\n\n\n\n<p>A\u00e7\u00f5es para reformula\u00e7\u00e3o das salas de aula na Rede Municipal<\/p>\n\n\n\n<p>Notebook<\/p>\n\n\n\n<p>A Secretaria de Educa\u00e7\u00e3o de Indaiatuba est\u00e1 substituindo 1.300 notebooks para os professores da Rede Municipal de Ensino. O investimento da a\u00e7\u00e3o \u00e9 de 10 milh\u00f5es e tem previs\u00e3o para conclus\u00e3o para 2022.<\/p>\n\n\n\n<p>Climatizares<\/p>\n\n\n\n<p>A Secretaria de Educa\u00e7\u00e3o de Indaiatuba est\u00e1 instalando aproximadamente 400 climatizares em todas as salas do 1\u00ba ao 5\u00ba ano do Ensino Fundamental I. A iniciativa visa proporcionar mais conforto para os alunos e professores, j\u00e1 que o clima no munic\u00edpio \u00e9 quente na maior parte do ano. O investimento total \u00e9 de R$ 3.607.041,00 e a previs\u00e3o da conclus\u00e3o do servi\u00e7o \u00e9 para o primeiro semestre de 2022. J\u00e1 est\u00e1 em processo licitat\u00f3rio a compra de mais 180 aparelhos para atender as salas da Etapa I e II.<\/p>\n\n\n\n<p>Google For Education<\/p>\n\n\n\n<p>A Secretaria de Educa\u00e7\u00e3o de Indaiatuba lan\u00e7ou no m\u00eas de outubro o Programa de Transforma\u00e7\u00e3o Digital Google For Education. A a\u00e7\u00e3o visa capacitar os profissionais da Rede Municipal de Ensino para a utiliza\u00e7\u00e3o de recursos tecnol\u00f3gicos como mais uma ferramenta para refor\u00e7ar e ampliar o processo de aprendizagem dos alunos. Foram investidos mais de R$ 2 milh\u00f5es na forma\u00e7\u00e3o que prev\u00ea 110 horas de curso e contemplar\u00e1 1.300 servidores.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A partir de 2022 a Secretaria de Educa\u00e7\u00e3o de Indaiatuba implantar\u00e1 o Sistema Sesi de Ensino para os alunos da Educa\u00e7\u00e3o Infantil (Etapas I e II) e Ensino Fundamental I (1\u00ba ao 5\u00ba ano). Essa \u00e9 mais uma a\u00e7\u00e3o que vem para somar a s\u00e9rie de reformula\u00e7\u00f5es que est\u00e3o sendo implantadas na Rede Municipal de [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":2837,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[188],"tags":[],"class_list":["post-2836","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-indaiatuba"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/posts\/2836","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/comments?post=2836"}],"version-history":[{"count":1,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/posts\/2836\/revisions"}],"predecessor-version":[{"id":2838,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/posts\/2836\/revisions\/2838"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/media\/2837"}],"wp:attachment":[{"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/media?parent=2836"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/categories?post=2836"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/imais.online\/portal\/wp-json\/wp\/v2\/tags?post=2836"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}